{"id":10073,"date":"2025-06-16T09:34:21","date_gmt":"2025-06-16T12:34:21","guid":{"rendered":"https:\/\/sertaneja95fm.com.br\/sited\/?p=10073"},"modified":"2025-06-16T09:34:21","modified_gmt":"2025-06-16T12:34:21","slug":"quadrilhas-entram-madrugada-adentro-no-ultimo-dia-do-forronovos-2025","status":"publish","type":"post","link":"https:\/\/sertaneja95fm.com.br\/sited\/quadrilhas-entram-madrugada-adentro-no-ultimo-dia-do-forronovos-2025\/","title":{"rendered":"Quadrilhas entram madrugada adentro no \u00faltimo dia do Forronovos 2025"},"content":{"rendered":"<p>O ritmo do forr\u00f3 e o brilho das tradi\u00e7\u00f5es juninas atravessaram a madrugada em Currais Novos. A grande final do\u00a0<strong>XXXI Festival de Quadrilhas Juninas<\/strong>\u00a0foi marcada por emo\u00e7\u00e3o, talento e resist\u00eancia, encerrando com chave de ouro o\u00a0<strong>Forronovos 2025<\/strong>, na manh\u00e3 desta segunda\u00a0<strong>(16)<\/strong>.<\/p>\n<p>O evento reuniu as melhores quadrilhas do estado nas categorias\u00a0<strong>estilizada e tradicional<\/strong>, que se apresentaram ao longo da noite e madrugada no pavilh\u00e3o montado na Pra\u00e7a de Ventos Monsenhor Aus\u00f4nio Ara\u00fajo (Pra\u00e7a da Imaculada).<\/p>\n<p>A \u00faltima apresenta\u00e7\u00e3o da noite \u2013 ou melhor, da manh\u00e3 \u2013 ficou por conta da\u00a0<strong>Quadrilha Arrai\u00e1 100% Ferrovi\u00e1rio<\/strong>, da cidade de\u00a0<strong>Lajes\/RN<\/strong>, que encerrou sua exibi\u00e7\u00e3o \u00e0s\u00a0<strong>5h15 da manh\u00e3<\/strong>. O p\u00fablico resistiu firme, vibrando e aplaudindo cada passo, figurino e encena\u00e7\u00e3o, num verdadeiro espet\u00e1culo cultural.<\/p>\n<p>A final do festival consagrou o Forronovos como um dos maiores e mais tradicionais eventos juninos do Rio Grande do Norte, reunindo milhares de pessoas e celebrando a cultura nordestina com intensidade e paix\u00e3o at\u00e9 os primeiros raios do sol.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ritmo do forr\u00f3 e o brilho das tradi\u00e7\u00f5es juninas atravessaram a madrugada em Currais Novos. A grande final do\u00a0XXXI Festival de Quadrilhas Juninas\u00a0foi marcada por emo\u00e7\u00e3o, talento e resist\u00eancia, encerrando com chave de ouro o\u00a0Forronovos 2025, na manh\u00e3 desta segunda\u00a0(16). O evento reuniu as melhores quadrilhas do estado nas categorias\u00a0estilizada e tradicional, que se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sertaneja95fm.com.br\/sited\/wp-json\/wp\/v2\/posts\/10073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sertaneja95fm.com.br\/sited\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sertaneja95fm.com.br\/sited\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sertaneja95fm.com.br\/sited\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sertaneja95fm.com.br\/sited\/wp-json\/wp\/v2\/comments?post=10073"}],"version-history":[{"count":1,"href":"https:\/\/sertaneja95fm.com.br\/sited\/wp-json\/wp\/v2\/posts\/10073\/revisions"}],"predecessor-version":[{"id":10075,"href":"https:\/\/sertaneja95fm.com.br\/sited\/wp-json\/wp\/v2\/posts\/10073\/revisions\/10075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sertaneja95fm.com.br\/sited\/wp-json\/wp\/v2\/media\/10074"}],"wp:attachment":[{"href":"https:\/\/sertaneja95fm.com.br\/sited\/wp-json\/wp\/v2\/media?parent=10073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sertaneja95fm.com.br\/sited\/wp-json\/wp\/v2\/categories?post=10073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sertaneja95fm.com.br\/sited\/wp-json\/wp\/v2\/tags?post=10073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}